{"id":856378,"name":"\u0393\u0399\u03a4\u03a3\u0391 \u03a0\u0391\u039d\u0391\u0393\u0399\u03a9\u03a4\u0391","url":"","description":"","link":"https:\/\/blogs.e-me.edu.gr\/hive-job-2024\/author\/panagitsa\/","slug":"panagitsa","avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/573536e8fbbde07f033607d1fbae9f69245aadd6736ff4c53eb383023c8df805?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/573536e8fbbde07f033607d1fbae9f69245aadd6736ff4c53eb383023c8df805?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/573536e8fbbde07f033607d1fbae9f69245aadd6736ff4c53eb383023c8df805?s=96&d=mm&r=g"},"meta":[],"_links":{"self":[{"href":"https:\/\/blogs.e-me.edu.gr\/hive-job-2024\/wp-json\/wp\/v2\/users\/856378","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.e-me.edu.gr\/hive-job-2024\/wp-json\/wp\/v2\/users"}]}}